{"id":23838,"date":"2026-05-06T11:12:55","date_gmt":"2026-05-06T09:12:55","guid":{"rendered":"https:\/\/www.dalminels.com\/?post_type=industrium_case&#038;p=23838"},"modified":"2026-05-06T12:19:28","modified_gmt":"2026-05-06T10:19:28","slug":"magazzini-generali-fiduciari-mantova","status":"publish","type":"industrium_case","link":"https:\/\/www.dalminels.com\/it\/case-studies\/magazzini-generali-fiduciari-mantova\/","title":{"rendered":"Magazzini Generali Fiduciari Mantova"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"23838\" class=\"elementor elementor-23838\" data-elementor-post-type=\"industrium_case\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1f449928 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"1f449928\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-500b5204\" data-id=\"500b5204\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2f8ea2ac elementor-widget__width-auto elementor-widget elementor-widget-post-info\" data-id=\"2f8ea2ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-inline-items elementor-icon-list-items elementor-post-info\">\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-8e71ce5 elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-tags\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-custom\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.dalminels.com\/it\/industrium_case_study_category\/food-beverage\/\" rel=\"tag\">Food &amp; Beverage<\/a>\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-56ef75a elementor-widget elementor-widget-spacer\" data-id=\"56ef75a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4aeda5f7 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"4aeda5f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Magazzini Generali Fiduciari Mantova<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44deb48c elementor-widget elementor-widget-spacer\" data-id=\"44deb48c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-956af7e elementor-widget elementor-widget-text-editor\" data-id=\"956af7e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">Da oltre 100 anni i Magazzini Generali Fiduciari di Mantova, societ\u00e0 del Gruppo Montepaschi, \u00e8 specializzata nei servizi di stagionatura e stoccaggio di formaggio a pasta dura, principalmente Parmigiano Reggiano e, in minor misura, Grana Padano.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4dbb048b elementor-widget elementor-widget-spacer\" data-id=\"4dbb048b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1a565b75\" data-id=\"1a565b75\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5853705e elementor-widget elementor-widget-spacer\" data-id=\"5853705e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-387b6c2b elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"387b6c2b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-4061048c\" data-id=\"4061048c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-44e49f2d elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"44e49f2d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"860\" height=\"645\" src=\"https:\/\/www.dalminels.com\/wp-content\/uploads\/2026\/05\/DALMINE-foto-case-studies_MGFM.jpg\" class=\"attachment-large size-large wp-image-23839\" alt=\"\" srcset=\"https:\/\/www.dalminels.com\/wp-content\/uploads\/2026\/05\/DALMINE-foto-case-studies_MGFM.jpg 860w, https:\/\/www.dalminels.com\/wp-content\/uploads\/2026\/05\/DALMINE-foto-case-studies_MGFM-300x225.jpg 300w, https:\/\/www.dalminels.com\/wp-content\/uploads\/2026\/05\/DALMINE-foto-case-studies_MGFM-768x576.jpg 768w, https:\/\/www.dalminels.com\/wp-content\/uploads\/2026\/05\/DALMINE-foto-case-studies_MGFM-640x479.jpg 640w, https:\/\/www.dalminels.com\/wp-content\/uploads\/2026\/05\/DALMINE-foto-case-studies_MGFM-480x359.jpg 480w, https:\/\/www.dalminels.com\/wp-content\/uploads\/2026\/05\/DALMINE-foto-case-studies_MGFM-384x287.jpg 384w, https:\/\/www.dalminels.com\/wp-content\/uploads\/2026\/05\/DALMINE-foto-case-studies_MGFM-320x239.jpg 320w\" sizes=\"(max-width: 860px) 100vw, 860px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-78490147 elementor-hidden-tablet_extra elementor-hidden-tablet elementor-hidden-mobile_extra elementor-hidden-mobile\" data-id=\"78490147\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-206d7761 elementor-widget elementor-widget-industrium_heading\" data-id=\"206d7761\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"industrium_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"industrium-heading-widget\"><h2 class=\"industrium-heading\"><span class=\"industrium-heading-content\">Richiedi ora informazioni o una consulenza<\/span><\/h2><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29bbdae elementor-widget elementor-widget-industrium_button\" data-id=\"29bbdae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"industrium_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"button-widget\">\n            <div class=\"button-container\">\n                <a class=\"industrium-button button-type-1\" href=\"https:\/\/www.dalminels.com\/contatti\/\" target=\"_blank\">\n                    Contattaci<svg viewBox=\"0 0 13 20\"><polyline points=\"0.5 19.5 3 19.5 12.5 10 3 0.5\"><\/polyline><\/svg>                    \n                <\/a>\n            <\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-328743a elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"328743a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2ebeb3a\" data-id=\"2ebeb3a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8523cd3 elementor-widget elementor-widget-heading\" data-id=\"8523cd3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">I numeri del progetto<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9663d67 elementor-widget elementor-widget-spacer\" data-id=\"9663d67\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8855553 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"8855553\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-9858c10\" data-id=\"9858c10\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0907483 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"0907483\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"119\" height=\"119\" src=\"https:\/\/www.dalminels.com\/wp-content\/uploads\/2024\/07\/dalmine_caoacita-di-stoccaggio.svg\" class=\"attachment-full size-full wp-image-16219\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">54.000<\/h3><p class=\"elementor-image-box-description\">forme da circa 400mm di diametro e 40kg di peso<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-d065d4f\" data-id=\"d065d4f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cdd0ad6 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"cdd0ad6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"119\" height=\"119\" src=\"https:\/\/www.dalminels.com\/wp-content\/uploads\/2024\/07\/dalmine_sltezza.svg\" class=\"attachment-full size-full wp-image-16220\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">22<\/h3><p class=\"elementor-image-box-description\">Livelli<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-c84a1bf\" data-id=\"c84a1bf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-62696aa elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"62696aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"119\" height=\"119\" src=\"https:\/\/www.dalminels.com\/wp-content\/uploads\/2024\/07\/dalmine_unita-di-stoccaggio.svg\" class=\"attachment-full size-full wp-image-16222\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">forme di formaggio<\/h3><p class=\"elementor-image-box-description\">Unit\u00e0 di carico<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-61944556 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"61944556\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3eabe142\" data-id=\"3eabe142\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1d8b70d1 elementor-widget elementor-widget-heading\" data-id=\"1d8b70d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Esigenze<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e63743b elementor-widget elementor-widget-spacer\" data-id=\"e63743b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5beef4c4 elementor-widget elementor-widget-text-editor\" data-id=\"5beef4c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>MGFM si contraddistingue per fornire un servizio all\u2019avanguardia nel rispetto dei disciplinari che regolano il settore della stagionatura:<br \/>&#8211; <a href=\"https:\/\/www.parmigianoreggiano.com\/it\" target=\"_blank\" rel=\"noopener\">https:\/\/www.parmigianoreggiano.com\/it<\/a><br \/>&#8211; <a href=\"https:\/\/www.granapadano.it\/it-it\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.granapadano.it\/it-it\/<\/a><\/p><p>Il nuovo impianto di scalere sorge in estensione ad uno precedente per soddisfare la crescita di richiesta di posti forma con la garanzia del mantenimento delle condizioni ambientali e della sicurezza delle lavorazioni da effettuare (spazzolatura, rivoltamento, battitura, marchiatura).<\/p><p>Per il sito di Suzzara, in provincia di Mantova, era necessaria una soluzione di stoccaggio massimo capace di ottimizzare i flussi, rispondendo alle operazioni giornaliere richieste rispettando le caratteristiche qualitative del prodotto.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1a76ee87 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"1a76ee87\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ecdcaf7\" data-id=\"ecdcaf7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-672e37ca elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"672e37ca\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-33aeb78b\" data-id=\"33aeb78b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-37273bef elementor-widget elementor-widget-heading\" data-id=\"37273bef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Le nostre Soluzioni<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ee765de elementor-widget elementor-widget-spacer\" data-id=\"3ee765de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-51c749d6 elementor-widget elementor-widget-text-editor\" data-id=\"51c749d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #ffffff;\">Per il magazzino di Suzzara abbiamo realizzato un impianto per lo stoccaggio e la movimentazione di 54.000 posti forma in un\u2019area di 1.850 mq con un\u2019altezza di circa 9,00 m. La struttura, asservita da macchine carica\/scarica e spazzolatrici, consente lo stoccaggio delle forme su tavole in legno massello di abete.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ae09865 elementor-section-boxed elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"ae09865\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-daa1652\" data-id=\"daa1652\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-de65f15 elementor-widget elementor-widget-heading\" data-id=\"de65f15\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Gallery<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dbb6f1b elementor-widget elementor-widget-spacer\" data-id=\"dbb6f1b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1b94b95 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no\" data-id=\"1b94b95\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b1fa358\" data-id=\"b1fa358\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f89788a elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"f89788a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;lazyload&quot;:&quot;yes&quot;,&quot;navigation&quot;:&quot;dots&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;image_spacing_custom_widescreen&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_tablet_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carosello d&#039;immagini\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 di 4\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/www.dalminels.com\/wp-content\/uploads\/2026\/05\/1.jpg\" alt=\"1\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 di 4\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/www.dalminels.com\/wp-content\/uploads\/2026\/05\/2.jpg\" alt=\"2\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 di 4\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/www.dalminels.com\/wp-content\/uploads\/2026\/05\/3.jpg\" alt=\"3\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 di 4\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/www.dalminels.com\/wp-content\/uploads\/2026\/05\/4.jpg\" alt=\"4\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Da oltre 100 anni i Magazzini Generali Fiduciari di Mantova, societ\u00e0 del Gruppo Montepaschi, \u00e8 specializzata nei servizi di stagionatura e stoccaggio di formaggio a pasta dura, principalmente Parmigiano Reggiano e, in minor misura, Grana Padano. I numeri del progetto 54.000&#8230;<\/p>\n","protected":false},"author":7,"featured_media":23839,"comment_status":"closed","ping_status":"closed","template":"","industrium_case_study_category":[45],"industrium_case_study_tag":[],"class_list":["post-23838","industrium_case","type-industrium_case","status-publish","has-post-thumbnail","hentry","industrium_case_study_category-food-beverage"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Magazzini Generali Fiduciari Mantova - Dalmine LS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.dalminels.com\/it\/case-studies\/magazzini-generali-fiduciari-mantova\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Magazzini Generali Fiduciari Mantova - Dalmine LS\" \/>\n<meta property=\"og:description\" content=\"Da oltre 100 anni i Magazzini Generali Fiduciari di Mantova, societ\u00e0 del Gruppo Montepaschi, \u00e8 specializzata nei servizi di stagionatura e stoccaggio di formaggio a pasta dura, principalmente Parmigiano Reggiano e, in minor misura, Grana Padano. I numeri del progetto 54.000...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.dalminels.com\/it\/case-studies\/magazzini-generali-fiduciari-mantova\/\" \/>\n<meta property=\"og:site_name\" content=\"Dalmine LS\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-06T10:19:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.dalminels.com\/wp-content\/uploads\/2026\/05\/DALMINE-foto-case-studies_MGFM.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"860\" \/>\n\t<meta property=\"og:image:height\" content=\"645\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.dalminels.com\/it\/case-studies\/magazzini-generali-fiduciari-mantova\/\",\"url\":\"https:\/\/www.dalminels.com\/it\/case-studies\/magazzini-generali-fiduciari-mantova\/\",\"name\":\"Magazzini Generali Fiduciari Mantova - Dalmine LS\",\"isPartOf\":{\"@id\":\"https:\/\/www.dalminels.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.dalminels.com\/it\/case-studies\/magazzini-generali-fiduciari-mantova\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.dalminels.com\/it\/case-studies\/magazzini-generali-fiduciari-mantova\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.dalminels.com\/wp-content\/uploads\/2026\/05\/DALMINE-foto-case-studies_MGFM.jpg\",\"datePublished\":\"2026-05-06T09:12:55+00:00\",\"dateModified\":\"2026-05-06T10:19:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.dalminels.com\/it\/case-studies\/magazzini-generali-fiduciari-mantova\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.dalminels.com\/it\/case-studies\/magazzini-generali-fiduciari-mantova\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.dalminels.com\/it\/case-studies\/magazzini-generali-fiduciari-mantova\/#primaryimage\",\"url\":\"https:\/\/www.dalminels.com\/wp-content\/uploads\/2026\/05\/DALMINE-foto-case-studies_MGFM.jpg\",\"contentUrl\":\"https:\/\/www.dalminels.com\/wp-content\/uploads\/2026\/05\/DALMINE-foto-case-studies_MGFM.jpg\",\"width\":860,\"height\":645},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.dalminels.com\/it\/case-studies\/magazzini-generali-fiduciari-mantova\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.dalminels.com\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Case Studies\",\"item\":\"https:\/\/www.dalminels.com\/it\/case-studies\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Magazzini Generali Fiduciari Mantova\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.dalminels.com\/it\/#website\",\"url\":\"https:\/\/www.dalminels.com\/it\/\",\"name\":\"Dalmine LS\",\"description\":\"We will Rack you!\",\"publisher\":{\"@id\":\"https:\/\/www.dalminels.com\/it\/#organization\"},\"alternateName\":\"Dalmime Logistic Solution\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.dalminels.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.dalminels.com\/it\/#organization\",\"name\":\"Dalmine LS\",\"alternateName\":\"Dalmine Logistic Solutions\",\"url\":\"https:\/\/www.dalminels.com\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.dalminels.com\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.dalminels.com\/wp-content\/uploads\/2024\/06\/Logo-dalmine-3-8.png\",\"contentUrl\":\"https:\/\/www.dalminels.com\/wp-content\/uploads\/2024\/06\/Logo-dalmine-3-8.png\",\"width\":487,\"height\":115,\"caption\":\"Dalmine LS\"},\"image\":{\"@id\":\"https:\/\/www.dalminels.com\/it\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/dalmine-logistic-solutions\",\"https:\/\/www.youtube.com\/channel\/UCSf7QoZzPlXVJSAUBkGiNJQ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Magazzini Generali Fiduciari Mantova - Dalmine LS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.dalminels.com\/it\/case-studies\/magazzini-generali-fiduciari-mantova\/","og_locale":"it_IT","og_type":"article","og_title":"Magazzini Generali Fiduciari Mantova - Dalmine LS","og_description":"Da oltre 100 anni i Magazzini Generali Fiduciari di Mantova, societ\u00e0 del Gruppo Montepaschi, \u00e8 specializzata nei servizi di stagionatura e stoccaggio di formaggio a pasta dura, principalmente Parmigiano Reggiano e, in minor misura, Grana Padano. I numeri del progetto 54.000...","og_url":"https:\/\/www.dalminels.com\/it\/case-studies\/magazzini-generali-fiduciari-mantova\/","og_site_name":"Dalmine LS","article_modified_time":"2026-05-06T10:19:28+00:00","og_image":[{"width":860,"height":645,"url":"https:\/\/www.dalminels.com\/wp-content\/uploads\/2026\/05\/DALMINE-foto-case-studies_MGFM.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.dalminels.com\/it\/case-studies\/magazzini-generali-fiduciari-mantova\/","url":"https:\/\/www.dalminels.com\/it\/case-studies\/magazzini-generali-fiduciari-mantova\/","name":"Magazzini Generali Fiduciari Mantova - Dalmine LS","isPartOf":{"@id":"https:\/\/www.dalminels.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.dalminels.com\/it\/case-studies\/magazzini-generali-fiduciari-mantova\/#primaryimage"},"image":{"@id":"https:\/\/www.dalminels.com\/it\/case-studies\/magazzini-generali-fiduciari-mantova\/#primaryimage"},"thumbnailUrl":"https:\/\/www.dalminels.com\/wp-content\/uploads\/2026\/05\/DALMINE-foto-case-studies_MGFM.jpg","datePublished":"2026-05-06T09:12:55+00:00","dateModified":"2026-05-06T10:19:28+00:00","breadcrumb":{"@id":"https:\/\/www.dalminels.com\/it\/case-studies\/magazzini-generali-fiduciari-mantova\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.dalminels.com\/it\/case-studies\/magazzini-generali-fiduciari-mantova\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.dalminels.com\/it\/case-studies\/magazzini-generali-fiduciari-mantova\/#primaryimage","url":"https:\/\/www.dalminels.com\/wp-content\/uploads\/2026\/05\/DALMINE-foto-case-studies_MGFM.jpg","contentUrl":"https:\/\/www.dalminels.com\/wp-content\/uploads\/2026\/05\/DALMINE-foto-case-studies_MGFM.jpg","width":860,"height":645},{"@type":"BreadcrumbList","@id":"https:\/\/www.dalminels.com\/it\/case-studies\/magazzini-generali-fiduciari-mantova\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.dalminels.com\/it\/"},{"@type":"ListItem","position":2,"name":"Case Studies","item":"https:\/\/www.dalminels.com\/it\/case-studies\/"},{"@type":"ListItem","position":3,"name":"Magazzini Generali Fiduciari Mantova"}]},{"@type":"WebSite","@id":"https:\/\/www.dalminels.com\/it\/#website","url":"https:\/\/www.dalminels.com\/it\/","name":"Dalmine LS","description":"We will Rack you!","publisher":{"@id":"https:\/\/www.dalminels.com\/it\/#organization"},"alternateName":"Dalmime Logistic Solution","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.dalminels.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.dalminels.com\/it\/#organization","name":"Dalmine LS","alternateName":"Dalmine Logistic Solutions","url":"https:\/\/www.dalminels.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.dalminels.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.dalminels.com\/wp-content\/uploads\/2024\/06\/Logo-dalmine-3-8.png","contentUrl":"https:\/\/www.dalminels.com\/wp-content\/uploads\/2024\/06\/Logo-dalmine-3-8.png","width":487,"height":115,"caption":"Dalmine LS"},"image":{"@id":"https:\/\/www.dalminels.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/dalmine-logistic-solutions","https:\/\/www.youtube.com\/channel\/UCSf7QoZzPlXVJSAUBkGiNJQ"]}]}},"_links":{"self":[{"href":"https:\/\/www.dalminels.com\/it\/wp-json\/wp\/v2\/industrium_case\/23838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dalminels.com\/it\/wp-json\/wp\/v2\/industrium_case"}],"about":[{"href":"https:\/\/www.dalminels.com\/it\/wp-json\/wp\/v2\/types\/industrium_case"}],"author":[{"embeddable":true,"href":"https:\/\/www.dalminels.com\/it\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dalminels.com\/it\/wp-json\/wp\/v2\/comments?post=23838"}],"version-history":[{"count":8,"href":"https:\/\/www.dalminels.com\/it\/wp-json\/wp\/v2\/industrium_case\/23838\/revisions"}],"predecessor-version":[{"id":23875,"href":"https:\/\/www.dalminels.com\/it\/wp-json\/wp\/v2\/industrium_case\/23838\/revisions\/23875"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dalminels.com\/it\/wp-json\/wp\/v2\/media\/23839"}],"wp:attachment":[{"href":"https:\/\/www.dalminels.com\/it\/wp-json\/wp\/v2\/media?parent=23838"}],"wp:term":[{"taxonomy":"industrium_case_study_category","embeddable":true,"href":"https:\/\/www.dalminels.com\/it\/wp-json\/wp\/v2\/industrium_case_study_category?post=23838"},{"taxonomy":"industrium_case_study_tag","embeddable":true,"href":"https:\/\/www.dalminels.com\/it\/wp-json\/wp\/v2\/industrium_case_study_tag?post=23838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}